{"id":1797,"count":1,"description":"","link":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/","name":"Mecolpress fiere","slug":"mecolpress-fiere","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mecolpress fiere Archives - Mecolpress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mecolpress fiere Archivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Mecolpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/en\\\/tag\\\/mecolpress-fiere\\\/\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/en\\\/tag\\\/mecolpress-fiere\\\/\",\"name\":\"Mecolpress fiere Archives - Mecolpress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/en\\\/tag\\\/mecolpress-fiere\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/en\\\/tag\\\/mecolpress-fiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mecolpress.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mecolpress fiere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/\",\"name\":\"Mecolpress\",\"description\":\"La Tecnologia della Forma\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mecolpress.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#organization\",\"name\":\"Mecolpress S.p.a.\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo_Mecolpress_RED-Copia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo_Mecolpress_RED-Copia.jpg\",\"width\":853,\"height\":516,\"caption\":\"Mecolpress S.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mecolpress\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mecolpress\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mecolpress-s.p.a.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mecolpressvideo\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mecolpress fiere Archives - Mecolpress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/","og_locale":"en_US","og_type":"article","og_title":"Mecolpress fiere Archivi","og_url":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/","og_site_name":"Mecolpress","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/","url":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/","name":"Mecolpress fiere Archives - Mecolpress","isPartOf":{"@id":"https:\/\/www.mecolpress.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mecolpress.com\/en\/tag\/mecolpress-fiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mecolpress.com\/en\/"},{"@type":"ListItem","position":2,"name":"Mecolpress fiere"}]},{"@type":"WebSite","@id":"https:\/\/www.mecolpress.com\/#website","url":"https:\/\/www.mecolpress.com\/","name":"Mecolpress","description":"La Tecnologia della Forma","publisher":{"@id":"https:\/\/www.mecolpress.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mecolpress.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mecolpress.com\/#organization","name":"Mecolpress S.p.a.","url":"https:\/\/www.mecolpress.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mecolpress.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2018\/11\/logo_Mecolpress_RED-Copia.jpg","contentUrl":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2018\/11\/logo_Mecolpress_RED-Copia.jpg","width":853,"height":516,"caption":"Mecolpress S.p.a."},"image":{"@id":"https:\/\/www.mecolpress.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mecolpress\/","https:\/\/www.instagram.com\/mecolpress","https:\/\/www.linkedin.com\/company\/mecolpress-s.p.a.","https:\/\/www.youtube.com\/user\/mecolpressvideo"]}]}},"_links":{"self":[{"href":"https:\/\/www.mecolpress.com\/en\/wp-json\/wp\/v2\/tags\/1797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mecolpress.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mecolpress.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mecolpress.com\/en\/wp-json\/wp\/v2\/posts?tags=1797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}