{"id":26681,"date":"2022-07-18T09:00:33","date_gmt":"2022-07-18T07:00:33","guid":{"rendered":"https:\/\/www.mecolpress.com\/?p=26681"},"modified":"2022-07-26T11:50:04","modified_gmt":"2022-07-26T09:50:04","slug":"seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno","status":"publish","type":"post","link":"https:\/\/www.mecolpress.com\/fr\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/","title":{"rendered":"SEO\/320: la pressa meccanica per lo stampaggio moderno"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-size: 21px;\">La nuova pressa meccanica di stampaggio a ciclo continuo e discontinuo<\/span><\/h2>\n<p>Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di <a href=\"https:\/\/www.mecolpress.com\/presse-meccaniche\/\" target=\"_blank\" rel=\"noopener\">pressa meccanica a ciclo continuo\\discontinuo di stampaggio<\/a>, <strong>taglia 320 tonnellate. <\/strong><\/p>\n<p>Questa macchina andr\u00e0 a migliorare le caratteristiche di tutte le precedenti macchine nel range dalle 200 alle 360 tonnellate. Da adesso in poi quindi una sola pressa potr\u00e0 garantire le prestazioni delle storiche SEO\/27 CVE-CS o le SEO\/36 CVE-CS, e sar\u00e0 appunto la nuova pressa meccanica SEO\/320!<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019esperienza maturata in questi 50 anni di attivit\u00e0 ci ha portato ogni giorno ad analizzare le esigenze di stampaggio di numerosi Clienti. La necessit\u00e0 principale che emerge \u00e8 che <strong>servono maggiori capacit\u00e0 di forza per deformare i nuovi materiali<\/strong>, senza piombo e decisamente pi\u00f9 altoresistenziali.<\/p>\n<p>Il risultato \u00e8 un modello di macchina totalmente rivoluzionario che racchiude tutte le migliorie apportate alle macchine storiche nel corso degli ultimi anni.<\/p>\n<p>LA SEO\/320 nasce per soddisfare tutte le nuove esigenze produttive figlie dei cambiamenti in atto nel mondo dello \u201cstampaggio moderno\u201d.[\/vc_column_text][vc_single_image image=\u00a0\u00bb26755&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-size: 21px;\">I problemi ricorrenti per uno stampatore<\/span><\/h2>\n<p>Se sei uno stampatore o sei titolare di una stamperia, ti sar\u00e0 capitato sicuramente di richiedere alla tua macchina prestazioni al limite per soddisfare i tuoi Clienti. Almeno su una delle tue presse, sar\u00e0 occorsa:<\/p>\n<ul class=\"disc\">\n<li>\u00a0la rottura degli ingranaggi e, in particolare, dei denti;<\/li>\n<li>\u00a0la rottura degli alberi di trasmissione;<\/li>\n<li>\u00a0la manutenzione su cuscini e frizioni\u2026<\/li>\n<\/ul>\n<p>Obbligandoti a dei fermi macchina inattesi, con tutti i disagi che ci\u00f2 ti avr\u00e0 arrecato![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-size: 21px;\">Soluzioni proposte da Mecolpress<\/span><\/h2>\n<p>I fermi macchina non possono sparire totalmente. Ricordiamoci che stiamo parlando di presse meccaniche che lavorano metalli ad alte temperature e possono essere soggette a sovraccarichi! Possono per\u00f2 essere drasticamente ridotti.<\/p>\n<blockquote><p>Perch\u00e9 spesso si dice che, anni fa, le macchine non si rompevano?<\/p><\/blockquote>\n<p>La risposta \u00e8 semplice! Erano dimensionate e studiate esattamente per le esigenze produttive di allora che non coincidono pi\u00f9 con quelle odierne!<\/p>\n<p>La risposta Mecolpress alle nuove prestazioni richieste nelle operazioni di stampaggio \u00e8 la nuova pressa SEO\/320 che \u00e8 ci\u00f2 di cui ogni stampatore necessita <strong><em>oggi<\/em><\/strong>![\/vc_column_text][vc_single_image image=\u00a0\u00bb26765&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-size: 21px;\">Caratteristiche Tecniche della Pressa meccanica SEO\/320<\/span><\/h2>\n<ul class=\"disc\">\n<li>La macchina ha una struttura monolitica in carpenteria saldata, per garantire la massima stabilit\u00e0 e la durata negli anni.<\/li>\n<li>Gli ingranaggi hanno una conformazione totalmente innovativa ed estremamente semplificata che non consiste soltanto nella maggiorazione dimensionale, come si potrebbe pensare, ma in una serie di miglioramenti che permettono alla macchina di lavorare alle massime prestazioni senza alcun rischio di rottura.<\/li>\n<li>Il cuscino \u00e8 stato semplificato, con l\u2019eliminazione delle regolazioni manuali e delle parti meccaniche soggette normalmente ad usura.<\/li>\n<li>Il volano \u00e8 stato progettato per garantire una sufficiente energia di deformazione anche a bassi giri. Questa particolare caratteristica \u00e8 molto apprezzata da chi deve stampare il materiale che richiedono basse velocit\u00e0 di deformazione.<\/li>\n<li>Abbiamo prestato molta attenzione all\u2019ergonomia: l\u2019operatore pu\u00f2 attrezzare la macchina velocemente e senza sforzi eccessivi. Troverai quindi una macchina senza spazi angusti con ampia visibilit\u00e0 e soprattutto sicura ed affidabile.<\/li>\n<\/ul>\n<h4 style=\"text-align: left;\"><span style=\"font-size: 14px;\">Riepiloghiamo nella seguente tabella le principali caratteristiche tecniche della nuova SEO\/320:<\/span><\/h4>\n<p>[\/vc_column_text][vc_single_image image=\u00a0\u00bb26893&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_single_image image=\u00a0\u00bb26760&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2><span style=\"font-size: 21px;\">Un\u2019opportunit\u00e0 per gli stampatori<\/span><\/h2>\n<p>Mecolpress offre a tutti i potenziali clienti la possibilit\u00e0 di <strong>visionare almeno una versione per ogni modello di macchina<\/strong> presso la sede produttiva di Flero (Brescia). Infatti, le principali versioni dei modelli pi\u00f9 richiesti sono sempre in produzione.<\/p>\n<p>Questo si traduce in un importante vantaggio per te Cliente perch\u00e9 ti viene offerta:<\/p>\n<ul class=\"disc\">\n<li>l\u2019opportunit\u00e0 di vedere e\/o provare le nostre macchine con il supporto del nostro personale specializzato a tua disposizione per chiarire qualsiasi dubbio o curiosit\u00e0;<\/li>\n<li>una data di consegna molto competitiva in caso d&rsquo;acquisto!<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_video link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=1mVEnx9cs5A\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb][vc_cta h2=\u00a0\u00bbFissa un appuntamento,\u00a0\u00bb h2_font_container=\u00a0\u00bbfont_size:20&Prime; h2_use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb h2_css_animation=\u00a0\u00bbfadeInLeft\u00a0\u00bb txt_align=\u00a0\u00bbcenter\u00a0\u00bb style=\u00a0\u00bb3d\u00a0\u00bb css_animation=\u00a0\u00bbfadeInLeft\u00a0\u00bb use_custom_fonts_h2=\u00a0\u00bbtrue\u00a0\u00bb h2_link=\u00a0\u00bburl:https%3A%2F%2Fwww.mecolpress.com%2Fcontatti%2F|title:Contatti\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18px;\"><a href=\"mailto:sales@mecolpress.com\">ti aspettiamo in MECOLPRESS!<\/a><\/span><\/p>\n<p>[\/vc_cta][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica a ciclo continuo\\discontinuo di stampaggio, taglia 320 tonnellate. <\/p>\n","protected":false},"author":4,"featured_media":26750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[76,9],"tags":[275,322,906,1684,31,1685],"class_list":["post-26681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-presse-meccaniche","tag-pressa-a-ciclo-continuo","tag-pressa-meccanica","tag-presse-stampaggio-a-caldo","tag-seo-320","tag-stampaggio-a-caldo","tag-stampaggio-moderno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mecolpress SEO\/320: la pressa meccanica per lo stampaggio moderno<\/title>\n<meta name=\"description\" content=\"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuodiscontinuo, taglia 320 tonnellate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEO\/320: la pressa meccanica per lo stampaggio moderno\" \/>\n<meta property=\"og:description\" content=\"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuodiscontinuo, taglia 320 tonnellate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/\" \/>\n<meta property=\"og:site_name\" content=\"Mecolpress\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mecolpress\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T07:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T09:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mecolpress\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mecolpress\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/\"},\"author\":{\"name\":\"Mecolpress\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/person\\\/cffb4bee00c73bc667f8397a4c930f14\"},\"headline\":\"SEO\\\/320: la pressa meccanica per lo stampaggio moderno\",\"datePublished\":\"2022-07-18T07:00:33+00:00\",\"dateModified\":\"2022-07-26T09:50:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/\"},\"wordCount\":770,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mecolpress-NUOVA-SEO-320.jpg\",\"keywords\":[\"pressa a ciclo continuo\",\"pressa meccanica\",\"presse stampaggio a caldo\",\"SEO 320\",\"stampaggio a caldo\",\"stampaggio moderno\"],\"articleSection\":[\"News\",\"Presse Meccaniche\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/\",\"name\":\"Mecolpress SEO\\\/320: la pressa meccanica per lo stampaggio moderno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mecolpress-NUOVA-SEO-320.jpg\",\"datePublished\":\"2022-07-18T07:00:33+00:00\",\"dateModified\":\"2022-07-26T09:50:04+00:00\",\"description\":\"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuo\\\\discontinuo, taglia 320 tonnellate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mecolpress-NUOVA-SEO-320.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mecolpress-NUOVA-SEO-320.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mecolpress.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEO\\\/320: la pressa meccanica per lo stampaggio moderno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/\",\"name\":\"Mecolpress\",\"description\":\"La Tecnologia della Forma\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mecolpress.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#organization\",\"name\":\"Mecolpress S.p.a.\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo_Mecolpress_RED-Copia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mecolpress.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/logo_Mecolpress_RED-Copia.jpg\",\"width\":853,\"height\":516,\"caption\":\"Mecolpress S.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mecolpress\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mecolpress\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mecolpress-s.p.a.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/mecolpressvideo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mecolpress.com\\\/#\\\/schema\\\/person\\\/cffb4bee00c73bc667f8397a4c930f14\",\"name\":\"Mecolpress\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g\",\"caption\":\"Mecolpress\"},\"url\":\"https:\\\/\\\/www.mecolpress.com\\\/fr\\\/author\\\/s-tonoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mecolpress SEO\/320: la pressa meccanica per lo stampaggio moderno","description":"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuodiscontinuo, taglia 320 tonnellate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/","og_locale":"fr_FR","og_type":"article","og_title":"SEO\/320: la pressa meccanica per lo stampaggio moderno","og_description":"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuodiscontinuo, taglia 320 tonnellate.","og_url":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/","og_site_name":"Mecolpress","article_publisher":"https:\/\/www.facebook.com\/mecolpress\/","article_published_time":"2022-07-18T07:00:33+00:00","article_modified_time":"2022-07-26T09:50:04+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","type":"image\/jpeg"}],"author":"Mecolpress","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mecolpress","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#article","isPartOf":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/"},"author":{"name":"Mecolpress","@id":"https:\/\/www.mecolpress.com\/#\/schema\/person\/cffb4bee00c73bc667f8397a4c930f14"},"headline":"SEO\/320: la pressa meccanica per lo stampaggio moderno","datePublished":"2022-07-18T07:00:33+00:00","dateModified":"2022-07-26T09:50:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/"},"wordCount":770,"publisher":{"@id":"https:\/\/www.mecolpress.com\/#organization"},"image":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","keywords":["pressa a ciclo continuo","pressa meccanica","presse stampaggio a caldo","SEO 320","stampaggio a caldo","stampaggio moderno"],"articleSection":["News","Presse Meccaniche"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/","url":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/","name":"Mecolpress SEO\/320: la pressa meccanica per lo stampaggio moderno","isPartOf":{"@id":"https:\/\/www.mecolpress.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#primaryimage"},"image":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","datePublished":"2022-07-18T07:00:33+00:00","dateModified":"2022-07-26T09:50:04+00:00","description":"Mecolpress \u00e8 orgogliosa di presentare un nuovo modello di pressa meccanica stampaggio a ciclo continuo\\discontinuo, taglia 320 tonnellate.","breadcrumb":{"@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#primaryimage","url":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","contentUrl":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.mecolpress.com\/seo-320-la-pressa-meccanica-per-lo-stampaggio-moderno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mecolpress.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SEO\/320: la pressa meccanica per lo stampaggio moderno"}]},{"@type":"WebSite","@id":"https:\/\/www.mecolpress.com\/#website","url":"https:\/\/www.mecolpress.com\/","name":"Mecolpress","description":"La Tecnologia della Forma","publisher":{"@id":"https:\/\/www.mecolpress.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mecolpress.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mecolpress.com\/#organization","name":"Mecolpress S.p.a.","url":"https:\/\/www.mecolpress.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mecolpress.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2018\/11\/logo_Mecolpress_RED-Copia.jpg","contentUrl":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2018\/11\/logo_Mecolpress_RED-Copia.jpg","width":853,"height":516,"caption":"Mecolpress S.p.a."},"image":{"@id":"https:\/\/www.mecolpress.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mecolpress\/","https:\/\/www.instagram.com\/mecolpress","https:\/\/www.linkedin.com\/company\/mecolpress-s.p.a.","https:\/\/www.youtube.com\/user\/mecolpressvideo"]},{"@type":"Person","@id":"https:\/\/www.mecolpress.com\/#\/schema\/person\/cffb4bee00c73bc667f8397a4c930f14","name":"Mecolpress","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56b9d501bc49aa0b1bd672cc74e17fee584bf7a497df81d9b164049f1a7fe9e8?s=96&d=mm&r=g","caption":"Mecolpress"},"url":"https:\/\/www.mecolpress.com\/fr\/author\/s-tonoli\/"}]}},"jetpack_featured_media_url":"https:\/\/www.mecolpress.com\/wp-content\/uploads\/2022\/06\/Mecolpress-NUOVA-SEO-320.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/posts\/26681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/comments?post=26681"}],"version-history":[{"count":52,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/posts\/26681\/revisions"}],"predecessor-version":[{"id":26899,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/posts\/26681\/revisions\/26899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/media\/26750"}],"wp:attachment":[{"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/media?parent=26681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/categories?post=26681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mecolpress.com\/fr\/wp-json\/wp\/v2\/tags?post=26681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}